{"id":113,"date":"2005-09-27T02:07:45","date_gmt":"2005-09-27T00:07:45","guid":{"rendered":"http:\/\/www.manq.it\/wordpress\/?p=113"},"modified":"2005-09-27T02:07:45","modified_gmt":"2005-09-27T00:07:45","slug":"ogni-tanto","status":"publish","type":"post","link":"https:\/\/www.manq.it\/index.php\/2005\/09\/27\/ogni-tanto\/","title":{"rendered":"Ogni tanto&#8230;"},"content":{"rendered":"<p align=\"justify\">&#8230; la mia vita mi fa schifo.<br \/>\nCredo siano le persone che mi circondano a rendere questi momenti non troppo frequenti.<br \/>\nTuttavia quando si \u00e8 da soli, in macchina, di notte, queste persone non ci sono ed \u00e8 in quei momenti che il peso dei pensieri si fa insostenibile.<br \/>\nCosa ne sto facendo della mia vita?<br \/>\nCredo di aver scelto il meno peggio dei modi per realizzare le aspettative che altri pongono su di me. Riuscir\u00f2 a non deluderli? Boh. Magari si, anche se in questo momento mi sento particolarmente propenso al fallimento. Se anche dovessi farcela, sar\u00f2 contento? E se lo sar\u00f2, lo sar\u00f2 per loro o per me?<br \/>\nSento forte una pressione che probabilmente nemmeno esiste.<br \/>\nBisogna reagire e passare oltre l&#8217;ostacolo. Come le altre volte. Una volta di pi\u00f9.<br \/>\nLo far\u00f2 domani, ora credo di non poter fare altro che piangermi addosso.<br \/>\nE questo non porta ad altro che a continuare a farmi schifo.<br \/>\nInesorabilmente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8230; la mia vita mi fa schifo. Credo siano le persone che mi circondano a rendere questi momenti non troppo frequenti. Tuttavia quando si \u00e8 da soli, in macchina, di notte, queste persone non ci sono ed \u00e8 in quei momenti che il peso dei pensieri si fa insostenibile. Cosa ne sto facendo della mia&hellip;&nbsp;<a href=\"https:\/\/www.manq.it\/index.php\/2005\/09\/27\/ogni-tanto\/\" rel=\"bookmark\">Leggi tutto &raquo;<span class=\"screen-reader-text\">Ogni tanto&#8230;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"categories":[4],"tags":[],"class_list":["post-113","post","type-post","status-publish","format-standard","hentry","category-riflessioni"],"_links":{"self":[{"href":"https:\/\/www.manq.it\/index.php\/wp-json\/wp\/v2\/posts\/113","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.manq.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.manq.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.manq.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.manq.it\/index.php\/wp-json\/wp\/v2\/comments?post=113"}],"version-history":[{"count":0,"href":"https:\/\/www.manq.it\/index.php\/wp-json\/wp\/v2\/posts\/113\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.manq.it\/index.php\/wp-json\/wp\/v2\/media?parent=113"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.manq.it\/index.php\/wp-json\/wp\/v2\/categories?post=113"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.manq.it\/index.php\/wp-json\/wp\/v2\/tags?post=113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}